{"id":19,"count":1,"description":"","link":"https:\/\/eyeball.co.jp\/en\/tag\/metallic-foil-pencils\/","name":"metallic foil pencils","slug":"metallic-foil-pencils","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/eyeball.co.jp\/en\/wp-json\/wp\/v2\/tags\/19","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eyeball.co.jp\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/eyeball.co.jp\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/eyeball.co.jp\/en\/wp-json\/wp\/v2\/posts?tags=19"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}